{"id":4434,"date":"2026-07-02T17:10:00","date_gmt":"2026-07-02T16:10:00","guid":{"rendered":"https:\/\/pascalchesnot.com\/index.php\/property\/moradia-excecional-renovada-grandola\/"},"modified":"2026-07-07T14:29:13","modified_gmt":"2026-07-07T13:29:13","slug":"moradia-excecional-renovada-grandola","status":"publish","type":"property","link":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/","title":{"rendered":"Moradia excecional renovada, Gr\u00e2ndola"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4434\" class=\"elementor elementor-4434 elementor-3384\" data-elementor-post-type=\"property\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc668d2 e-flex e-con-boxed e-con e-parent\" data-id=\"7bc668d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51ae73c8 elementor-widget elementor-widget-gallery\" data-id=\"51ae73c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:3,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/95_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"95_Gr\u00e2ndola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQzNSwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA5XC85NV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/95_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/89_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"89_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc1OSwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC84OV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/89_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/58_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"58_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2MSwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC81OF9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/58_Grandola-768x511.jpg\" data-width=\"768\" data-height=\"511\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/25_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"25_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc1NiwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC8yNV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/25_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/85_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"85_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc1OCwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC84NV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/85_Grandola-768x511.jpg\" data-width=\"768\" data-height=\"511\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/21_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"21_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2MCwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC8yMV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/21_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/54_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"54_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2MiwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC81NF9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/54_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/46_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"46_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2MywidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC80Nl9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/46_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/41_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"41_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2NCwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC80MV9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/41_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/07_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2NywidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC8wN19HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/07_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/68_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"68_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2NiwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC82OF9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/68_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/44_Grandola.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"51ae73c8\" data-elementor-lightbox-title=\"44_Grandola\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzc2NSwidXJsIjoiaHR0cDpcL1wvcGFzY2FsY2hlc25vdC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA3XC80NF9HcmFuZG9sYS5qcGciLCJzbGlkZXNob3ciOiI1MWFlNzNjOCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/07\/44_Grandola-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":4436,"template":"","meta":{"_acf_changed":false},"categories":[53],"class_list":["post-4434","property","type-property","status-publish","has-post-thumbnail","hentry","category-para-venda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot\" \/>\n<meta property=\"og:url\" content=\"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/\" \/>\n<meta property=\"og:site_name\" content=\"Pascal Chesnot\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T13:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/76_Grandola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/\",\"url\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/\",\"name\":\"Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/pascalchesnot.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/76_Grandola.jpg\",\"datePublished\":\"2026-07-02T16:10:00+00:00\",\"dateModified\":\"2026-07-07T13:29:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/#primaryimage\",\"url\":\"http:\\\/\\\/pascalchesnot.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/76_Grandola.jpg\",\"contentUrl\":\"http:\\\/\\\/pascalchesnot.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/76_Grandola.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/property\\\/moradia-excecional-renovada-grandola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moradia excecional renovada, Gr\u00e2ndola\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#website\",\"url\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/\",\"name\":\"Pascal Chesnot\",\"description\":\"Real Estate Consulting &amp; Global Solution\",\"publisher\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#organization\",\"name\":\"Pascal Chesnot\",\"url\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/pascalchesnot.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/LOGO-BLEU-FOND-TRANSPARENT-1.png\",\"contentUrl\":\"http:\\\/\\\/pascalchesnot.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/LOGO-BLEU-FOND-TRANSPARENT-1.png\",\"width\":1556,\"height\":723,\"caption\":\"Pascal Chesnot\"},\"image\":{\"@id\":\"http:\\\/\\\/pascalchesnot.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/","og_locale":"pt_PT","og_type":"article","og_title":"Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot","og_url":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/","og_site_name":"Pascal Chesnot","article_modified_time":"2026-07-07T13:29:13+00:00","og_image":[{"width":1500,"height":1000,"url":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/76_Grandola.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/","url":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/","name":"Moradia excecional renovada, Gr\u00e2ndola - Pascal Chesnot","isPartOf":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/#primaryimage"},"image":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/#primaryimage"},"thumbnailUrl":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/76_Grandola.jpg","datePublished":"2026-07-02T16:10:00+00:00","dateModified":"2026-07-07T13:29:13+00:00","breadcrumb":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/#primaryimage","url":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/76_Grandola.jpg","contentUrl":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2025\/09\/76_Grandola.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"http:\/\/pascalchesnot.com\/pt-pt\/property\/moradia-excecional-renovada-grandola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/pascalchesnot.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Moradia excecional renovada, Gr\u00e2ndola"}]},{"@type":"WebSite","@id":"http:\/\/pascalchesnot.com\/pt-pt\/#website","url":"http:\/\/pascalchesnot.com\/pt-pt\/","name":"Pascal Chesnot","description":"Real Estate Consulting &amp; Global Solution","publisher":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/pascalchesnot.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"http:\/\/pascalchesnot.com\/pt-pt\/#organization","name":"Pascal Chesnot","url":"http:\/\/pascalchesnot.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"http:\/\/pascalchesnot.com\/pt-pt\/#\/schema\/logo\/image\/","url":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2021\/11\/LOGO-BLEU-FOND-TRANSPARENT-1.png","contentUrl":"http:\/\/pascalchesnot.com\/wp-content\/uploads\/2021\/11\/LOGO-BLEU-FOND-TRANSPARENT-1.png","width":1556,"height":723,"caption":"Pascal Chesnot"},"image":{"@id":"http:\/\/pascalchesnot.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/property\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/property"}],"about":[{"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/types\/property"}],"version-history":[{"count":4,"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/property\/4434\/revisions"}],"predecessor-version":[{"id":6750,"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/property\/4434\/revisions\/6750"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/media\/4436"}],"wp:attachment":[{"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=4434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/pascalchesnot.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}